{"id":15979,"date":"2023-06-14T12:48:55","date_gmt":"2023-06-14T12:48:55","guid":{"rendered":"https:\/\/www.ibermusicas.org\/?p=15979"},"modified":"2023-06-29T13:09:37","modified_gmt":"2023-06-29T13:09:37","slug":"rios-la-red-iberoamericana-de-orquestas-sinfonicas-anuncia-sus-proximas-actividades","status":"publish","type":"post","link":"https:\/\/www.ibermusicas.org\/index.php\/rios-la-red-iberoamericana-de-orquestas-sinfonicas-anuncia-sus-proximas-actividades\/","title":{"rendered":"RIOS, la Red Iberoamericana de Orquestas Sinf\u00f3nicas, anuncia sus pr\u00f3ximas actividades"},"content":{"rendered":"<p>El 22 de junio los miembros de RIOS realizar\u00e1 su primera reuni\u00f3n para compartir repertorio de compositores iberoamericanos con las propuestas de los Mtros. Diego S\u00e1nchez Haase (Orquesta del Congreso de la Naci\u00f3n, Paraguay) y Jos\u00e9 Ram\u00edrez Duarte (Orquesta Sinf\u00f3nica Nacional de Paraguay).<\/p>\n<p>&nbsp;<\/p>\n<p>El 29\u00a0 de junio se realizar\u00e1 la primera reuni\u00f3n de los representantes de \u00e1reas educativas y de extensi\u00f3n de las orquestas de RIOS y de todos los interesados en profundizar en el tema. Con la coordinaci\u00f3n de Monique Andreis de la Orquesta Sinf\u00f3nica Petrobras, se compartir\u00e1n experiencias y propuestas dirigidas a realizar acciones conjuntas y dar apoyo a quienes lo necesiten en una tem\u00e1tica que resulta crucial para la actividad sinf\u00f3nica.<\/p>\n<p>&nbsp;<\/p>\n<p>La Red Iberoamericana de Orquestas Sinf\u00f3nicas (RIOS) es la organizaci\u00f3n que conecta a las orquestas profesionales de la regi\u00f3n, bajo el auspicio del Programa Iberm\u00fasicas. Su prop\u00f3sito es servir de referente a las orquestas sinf\u00f3nicas en Iberoam\u00e9rica, articulando proyectos en la regi\u00f3n y con el resto del mundo, y llevando adelante una agenda com\u00fan de acciones conjuntas para el fomento de las instituciones y la actividad sinf\u00f3nica.<\/p>\n<p>&nbsp;<\/p>\n<p>Su misi\u00f3n es impulsar el desarrollo de la m\u00fasica sinf\u00f3nica como pr\u00e1ctica profesional en la regi\u00f3n, propiciando la integraci\u00f3n y cooperaci\u00f3n institucional, con herramientas que aporten al fomento de la m\u00fasica orquestal, al intercambio de conocimiento, a la identificaci\u00f3n de desaf\u00edos y a la coordinaci\u00f3n de agendas.<\/p>\n<p>&nbsp;<\/p>\n<p>RIOS es un espacio convergente para las orquestas profesionales iberoamericanas. Sus miembros se convocan en una cooperaci\u00f3n inclusiva, solidaria y consensuada con el objetivo de consolidar un espacio de di\u00e1logo permanente.<\/p>\n<p>&nbsp;<\/p>\n<p>M\u00e1s informaci\u00f3n en: rios.orquestas@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 22 de junio los miembros de RIOS realizar\u00e1 su primera reuni\u00f3n para compartir repertorio de compositores iberoamericanos con las propuestas de los Mtros. Diego S\u00e1nchez Haase (Orquesta del Congreso de la Naci\u00f3n, Paraguay) y Jos\u00e9 Ram\u00edrez Duarte (Orquesta Sinf\u00f3nica Nacional de Paraguay). &nbsp; El 29\u00a0 de junio se realizar\u00e1 la primera reuni\u00f3n de los [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":15980,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-15979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-generales"],"lang":"es","translations":{"es":15979,"pt":15982},"pll_sync_post":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/15979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/comments?post=15979"}],"version-history":[{"count":0,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/15979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media\/15980"}],"wp:attachment":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media?parent=15979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/categories?post=15979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/tags?post=15979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}