{"id":16569,"date":"2023-08-11T18:53:21","date_gmt":"2023-08-11T18:53:21","guid":{"rendered":"https:\/\/www.ibermusicas.org\/?p=16569"},"modified":"2023-08-30T21:52:23","modified_gmt":"2023-08-30T21:52:23","slug":"la-artista-y-productora-cultural-isabella-bretz-presenta-el-proyecto-iniciativas-feministas-en-la-musica-en-paises-iberoamericanos","status":"publish","type":"post","link":"https:\/\/www.ibermusicas.org\/index.php\/la-artista-y-productora-cultural-isabella-bretz-presenta-el-proyecto-iniciativas-feministas-en-la-musica-en-paises-iberoamericanos\/","title":{"rendered":"La artista y productora cultural Isabella Bretz presenta el proyecto \u00abIniciativas feministas en la m\u00fasica en pa\u00edses iberoamericanos\u00bb"},"content":{"rendered":"<p>Isabella Bretz propone la realizaci\u00f3n de la investigaci\u00f3n \u00abIniciativas feministas en la m\u00fasica en los pa\u00edses iberoamericanos\u00bb, que se llevar\u00e1 a cabo en colaboraci\u00f3n con la artista brasile\u00f1a Deh Muss. Las artistas y productoras utilizar\u00e1n sus experiencias y conocimientos acad\u00e9micos y pr\u00e1cticos para trazar un mapa de las acciones llevadas a cabo por mujeres compositoras en la regi\u00f3n iberoamericana.<\/p>\n<p>&nbsp;<\/p>\n<p>Estos datos se compartir\u00e1n con toda la red Sonora y se colocar\u00e1n en un mapa en sonorafestival.com. En el futuro, se pretende crear un mapa interactivo con estos datos y crear mecanismos que favorezcan la conexi\u00f3n entre iniciativas.<\/p>\n<p>&nbsp;<\/p>\n<p>La red Sonora est\u00e1 formada por mujeres de diferentes colores, orientaciones sexuales, religiones y entornos socioecon\u00f3micos. Actualmente, la red ya ha llegado a 74 ciudades en 16 pa\u00edses y contin\u00faa con su objetivo central de dar visibilidad, promover y legitimar la presencia de mujeres compositoras, empoder\u00e1ndolas art\u00edstica, profesional y econ\u00f3micamente, contribuyendo a la reducci\u00f3n de la desigualdad de g\u00e9nero en el \u00e1mbito musical.<\/p>\n<p>&nbsp;<\/p>\n<p>El proyecto result\u00f3 ganador de las convocatorias 2022 del Programa Iberm\u00fasicas en la l\u00ednea \u00abAyudas al Sector Musical en Modalidad Virtual\u00bb.<\/p>\n<p>19 de agosto: divulgaci\u00f3n de los resultados de la investigaci\u00f3n<\/p>\n<p>https:\/\/www.instagram.com\/sonorafestivalinternacional\/<\/p>\n<p>sonorafestival.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isabella Bretz propone la realizaci\u00f3n de la investigaci\u00f3n \u00abIniciativas feministas en la m\u00fasica en los pa\u00edses iberoamericanos\u00bb, que se llevar\u00e1 a cabo en colaboraci\u00f3n con la artista brasile\u00f1a Deh Muss. Las artistas y productoras utilizar\u00e1n sus experiencias y conocimientos acad\u00e9micos y pr\u00e1cticos para trazar un mapa de las acciones llevadas a cabo por mujeres compositoras [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":16570,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-16569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-generales"],"lang":"es","translations":{"es":16569,"pt":16572},"pll_sync_post":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/16569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/comments?post=16569"}],"version-history":[{"count":0,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/16569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media\/16570"}],"wp:attachment":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media?parent=16569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/categories?post=16569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/tags?post=16569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}