{"id":28208,"date":"2026-05-13T20:05:42","date_gmt":"2026-05-13T20:05:42","guid":{"rendered":"https:\/\/www.ibermusicas.org\/?p=28208"},"modified":"2026-05-13T20:06:11","modified_gmt":"2026-05-13T20:06:11","slug":"realizado-na-colombia-o-xxiii-conselho-intergovernamental-do-programa-ibermusicas","status":"publish","type":"post","link":"https:\/\/www.ibermusicas.org\/index.php\/realizado-na-colombia-o-xxiii-conselho-intergovernamental-do-programa-ibermusicas\/","title":{"rendered":"Realizado na Col\u00f4mbia o XXIII Conselho Intergovernamental do Programa IBERM\u00daSICAS"},"content":{"rendered":"\n<p>Nos dias 6, 7, 8 e 9 de maio de 2026, no Pal\u00e1cio da Proclama\u00e7\u00e3o da Cidade de Cartagena das \u00cdndias, Col\u00f4mbia, ocorreu o <strong>Vig\u00e9simo Terceiro Conselho Intergovernamental do Programa Iberm\u00fasicas<\/strong>. O evento contou com a participa\u00e7\u00e3o de representantes da Argentina, Brasil, Chile, Col\u00f4mbia, Costa Rica, Cuba, Equador, El Salvador, Espanha, M\u00e9xico, Panam\u00e1, Paraguai, Peru, Portugal, Uruguai, Venezuela, SEGIB (Secretaria-Geral Ibero-Americana), a Unidade T\u00e9cnica Iberm\u00fasicas e a Guatemala como pa\u00eds convidado.<\/p>\n\n\n\n<p>As quatro jornadas contaram com a presen\u00e7a de autoridades regionais e nacionais:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vaneza Daguer Tamayo, diretora do Instituto de Cultura e Turismo de Bol\u00edvar<\/li>\n\n\n\n<li>Fabi\u00e1n S\u00e1nchez Molina, Vice-Ministro das Culturas, das Artes e dos Saberes da Col\u00f4mbia<\/li>\n\n\n\n<li>Maira Salamanca, Diretora de Artes do Minist\u00e9rio das Culturas, das Artes e dos Saberes da Col\u00f4mbia<\/li>\n\n\n\n<li>Jorge Sossa Santos, Coordenador do Grupo de M\u00fasica, Dire\u00e7\u00e3o de Artes do Minist\u00e9rio das Culturas, das Artes e dos Saberes<\/li>\n<\/ul>\n\n\n\n<p><strong>Esta reuni\u00e3o constituiu uma inst\u00e2ncia fundamental para analisar conjuntamente a trajet\u00f3ria do Programa, avaliando o impacto, o desenvolvimento e o desempenho das linhas de a\u00e7\u00e3o implementadas, com o prop\u00f3sito de fortalecer sua orienta\u00e7\u00e3o estrat\u00e9gica e aprofundar seu alcance na regi\u00e3o ibero-americana<\/strong>.<\/p>\n\n\n\n<p>A agenda desta edi\u00e7\u00e3o esteve especialmente voltada para a aprova\u00e7\u00e3o do Plano Operativo Anual (POA), bem como para a apresenta\u00e7\u00e3o de resultados, a an\u00e1lise das convocat\u00f3rias e os projetos de coopera\u00e7\u00e3o, promovendo uma vis\u00e3o compartilhada que consolide o Programa como uma ferramenta estrat\u00e9gica de coopera\u00e7\u00e3o cultural na regi\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>Revis\u00e3o do que foi realizado em 2025:<strong><\/strong><\/h3>\n\n\n\n<p>Durante o per\u00edodo de 2025, o Programa Iberm\u00fasicas consolidou um conjunto de iniciativas que refletem uma <strong>estrat\u00e9gia integral orientada a fortalecer a circula\u00e7\u00e3o, a coopera\u00e7\u00e3o internacional e o desenvolvimento do setor musical ibero-americano.<\/strong> Por meio dos <strong>Projetos Especiais Pa\u00eds (PeP)<\/strong>, foram impulsionadas a\u00e7\u00f5es de alto impacto que permitiram projetar as m\u00fasicas nacionais no \u00e2mbito global, promover a diversidade cultural e valorizar patrim\u00f4nios musicais identit\u00e1rios.<\/p>\n\n\n\n<p>Paralelamente, registraram-se avan\u00e7os significativos no desenvolvimento de ferramentas estruturais do Programa, tais como: o Cat\u00e1logo Ibero-americano de Partituras, a plataforma Iberm\u00fasicas Global, a\u00e7\u00f5es de comunica\u00e7\u00e3o digital, consolidando dispositivos que ampliam a visibilidade, a conex\u00e3o profissional e o acesso a novos mercados.<\/p>\n\n\n\n<p>Da mesma forma, o Programa aprofundou seu posicionamento por meio da participa\u00e7\u00e3o em mercados internacionais e do desenvolvimento de sinergias estrat\u00e9gicas com organismos e regi\u00f5es, fortalecendo a presen\u00e7a de artistas ibero-americanos em circuitos globais. Esta<strong>s a\u00e7\u00f5es foram complementadas pelo impulso de redes como a RIOS, <\/strong>avan\u00e7os nas estreias de obras premiadas e o desenvolvimento de pol\u00edticas transversais em acessibilidade, inclus\u00e3o e g\u00eanero.<\/p>\n\n\n\n<p>Em paralelo, avan\u00e7ou-se na gera\u00e7\u00e3o de conhecimento e ferramentas de planejamento \u2014 como a an\u00e1lise de convocat\u00f3rias, o desenvolvimento de novos regulamentos e o desenho do Plano Operativo Anual \u2014, juntamente com a <strong>promo\u00e7\u00e3o de novas linhas de forma\u00e7\u00e3o em \u00e1reas emergentes, como a sincroniza\u00e7\u00e3o musical<\/strong> e a <strong>m\u00fasica para videogames<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>2026-2027<strong><\/strong><\/h3>\n\n\n\n<p>Para o per\u00edodo pr\u00f3ximo, o Programa Iberm\u00fasicas se prop\u00f5e a <strong>aprofundar sua proje\u00e7\u00e3o internacional, fortalecer seus instrumentos de gest\u00e3o e ampliar suas linhas de a\u00e7\u00e3o estrat\u00e9gicas,<\/strong> consolidando seu papel como plataforma de coopera\u00e7\u00e3o cultural na regi\u00e3o. Nesse sentido, prev\u00ea-se avan\u00e7ar no desenvolvimento de <strong>novas sinergias e alian\u00e7as institucionais com pa\u00edses de fora da regi\u00e3o,<\/strong> bem como no fortalecimento das articula\u00e7\u00f5es com outros Programas Iber e redes institucionais, promovendo uma maior integra\u00e7\u00e3o entre setores e territ\u00f3rios.<\/p>\n\n\n\n<p>Da mesma forma, buscar-se-\u00e1 <strong>otimizar os instrumentos do Programa <\/strong>a partir da an\u00e1lise do alcance das convocat\u00f3rias de 2025 e do desenho dos regulamentos de 2026, incorporando aprendizados e evid\u00eancias que permitam melhorar seu impacto. Em paralelo, ser\u00e1 impulsionada a gera\u00e7\u00e3o de conhecimento estrat\u00e9gico mediante o desenvolvimento de um estudo regional junto a parceiros estrat\u00e9gicos sobre o impacto econ\u00f4mico do setor musical, bem como a participa\u00e7\u00e3o em iniciativas internacionais com projetos especiais.<\/p>\n\n\n\n<p>Em mat\u00e9ria de forma\u00e7\u00e3o e profissionaliza\u00e7\u00e3o, projeta-se o desenvolvimento<strong> de novas linhas de capacita\u00e7\u00e3o em \u00e1reas-chave da ind\u00fastria contempor\u00e2nea,<\/strong> tais como a sincroniza\u00e7\u00e3o musical e a cria\u00e7\u00e3o musical para videogames, em articula\u00e7\u00e3o com parceiros especializados. Estas a\u00e7\u00f5es ser\u00e3o complementadas com iniciativas estruturais no \u00e2mbito da RIOS, como a Diplomatura em Gest\u00e3o Orquestral, a Plataforma Ibero-americana para Diretores de Orquestra e o programa \u201cResson\u00e2ncias da Ibero-am\u00e9rica\u201d, orientadas a fortalecer capacidades e gerar modelos de forma\u00e7\u00e3o de alcance regional.<\/p>\n\n\n\n<p>Por outro lado, avan\u00e7ar-se-\u00e1 em projetos orientados \u00e0 <strong>preserva\u00e7\u00e3o e valoriza\u00e7\u00e3o do patrim\u00f4nio musical,<\/strong> como a digitaliza\u00e7\u00e3o de partituras de m\u00fasica antiga ibero-americana em colabora\u00e7\u00e3o com aliados especializados, bem como em iniciativas de alcance transversal como a Cartografia de g\u00eanero no setor cultural ibero-americano, que permitir\u00e1 identificar lacunas e orientar pol\u00edticas para uma maior equidade.<\/p>\n\n\n\n<p>Finalmente, ser\u00e3o promovidas novas alian\u00e7as estrat\u00e9gicas orientadas a fortalecer a circula\u00e7\u00e3o de conhecimento, ampliar o alcance dos recursos gerados e consolidar v\u00ednculos institucionais sustent\u00e1veis.<\/p>\n\n\n\n<p>Este conjunto de a\u00e7\u00f5es reflete a vontade do Programa de <strong>ampliar seu impacto, diversificar suas ferramentas e consolidar uma estrat\u00e9gia integral<\/strong> que articule coopera\u00e7\u00e3o, forma\u00e7\u00e3o, circula\u00e7\u00e3o e produ\u00e7\u00e3o de conhecimento, em resposta aos desafios atuais do setor musical ibero-americano.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos dias 6, 7, 8 e 9 de maio de 2026, no Pal\u00e1cio da Proclama\u00e7\u00e3o da Cidade de Cartagena das \u00cdndias, Col\u00f4mbia, ocorreu o Vig\u00e9simo Terceiro Conselho Intergovernamental do Programa Iberm\u00fasicas. O evento contou com a participa\u00e7\u00e3o de representantes da Argentina, Brasil, Chile, Col\u00f4mbia, Costa Rica, Cuba, Equador, El Salvador, Espanha, M\u00e9xico, Panam\u00e1, Paraguai, Peru, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[218,220,222],"tags":[],"class_list":["post-28208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-generales-pt","category-noticias-ibermusicas-pt","category-noticias-rotativas-pt"],"lang":"pt","translations":{"pt":28208,"es":28205},"pll_sync_post":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/28208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/comments?post=28208"}],"version-history":[{"count":2,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/28208\/revisions"}],"predecessor-version":[{"id":28211,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/28208\/revisions\/28211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media\/28206"}],"wp:attachment":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media?parent=28208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/categories?post=28208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/tags?post=28208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}