{"id":5449,"date":"2021-04-08T17:56:39","date_gmt":"2021-04-08T17:56:39","guid":{"rendered":"https:\/\/www.ibermusicas.org\/?p=5449"},"modified":"2021-05-04T17:29:23","modified_gmt":"2021-05-04T17:29:23","slug":"hemiola-musicas-de-chile-inicia-sus-talleres-virtuales-arrullos-de-infancia-y-juegos-ritmicos-de-latinoamerica","status":"publish","type":"post","link":"https:\/\/www.ibermusicas.org\/index.php\/hemiola-musicas-de-chile-inicia-sus-talleres-virtuales-arrullos-de-infancia-y-juegos-ritmicos-de-latinoamerica\/","title":{"rendered":"HEMIOLA M\u00daSICAS DE CHILE, INICIA SUS TALLERES VIRTUALES \u201cARRULLOS DE INFANCIA Y JUEGOS R\u00cdTMICOS DE LATINOAM\u00c9RICA\u201d"},"content":{"rendered":"<p>Estos talleres invitan a vivenciar una selecci\u00f3n especial de canciones y versos en claves de ritmos latinoamericanos, destinadas a ser recibidas a modo de \u201carrullo\u201d de infancia, donde el trenzado de canto, la melod\u00eda y el ritmo propio de cada canci\u00f3n se vuelve soporte de cobijo, (auto) cuidado y seguridad tanto para sus destinatarios (ni\u00f1os) como para sus int\u00e9rpretes. Ser\u00e1n 10 encuentros en los que se estudiar\u00e1n las canciones a partir de din\u00e1micas l\u00fadicas y creativas donde el juego ser\u00e1 el eje y la metodolog\u00eda esencial del aprendizaje a partir del disfrute.<\/p>\n<p>Cada Canci\u00f3n ser\u00e1 acompa\u00f1ada de un relato Antropol\u00f3gico Musical, que d\u00e9 cuenta de su contexto, origen, historia y significancia humana para la comunidad que la acun\u00f3.<\/p>\n<p>Los talleres estar\u00e1n a cargo de Carolina Chacana, music\u00f3loga y pedagoga Waldorf chilena y Juan Carlos Ochoa, percusionista colombiano. Se realizar\u00e1n a trav\u00e9s de la Plataforma Zoom y tendr\u00e1n una duraci\u00f3n de aproximadamente 2 horas. Ser\u00e1n en total 10 encuentros comprendidos entre los meses de abril y diciembre con un cierre final.<\/p>\n<p>Comienza: s\u00e1bado 24 de abril. Cupos limitados<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estos talleres invitan a vivenciar una selecci\u00f3n especial de canciones y versos en claves de ritmos latinoamericanos, destinadas a ser recibidas a modo de \u201carrullo\u201d de infancia, donde el trenzado de canto, la melod\u00eda y el ritmo propio de cada canci\u00f3n se vuelve soporte de cobijo, (auto) cuidado y seguridad tanto para sus destinatarios (ni\u00f1os) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-5449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-generales"],"lang":"es","translations":{"es":5449,"pt":5452},"pll_sync_post":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/5449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/comments?post=5449"}],"version-history":[{"count":0,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/5449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media\/5450"}],"wp:attachment":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media?parent=5449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/categories?post=5449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/tags?post=5449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}