{"id":7041,"date":"2017-09-07T11:51:45","date_gmt":"2017-09-07T11:51:45","guid":{"rendered":"https:\/\/www.ibermusicas.org\/?p=7041"},"modified":"2021-06-14T11:53:50","modified_gmt":"2021-06-14T11:53:50","slug":"el-compositor-argentino-fernando-garnero-inicia-su-residencia-compositiva-en-el-bifem-de-australia-con-vistas-al-estreno-de-su-obra-neon-pig","status":"publish","type":"post","link":"https:\/\/www.ibermusicas.org\/index.php\/el-compositor-argentino-fernando-garnero-inicia-su-residencia-compositiva-en-el-bifem-de-australia-con-vistas-al-estreno-de-su-obra-neon-pig\/","title":{"rendered":"El compositor argentino Fernando Garnero inicia su residencia compositiva en el BIFEM de Australia con vistas al estreno de su obra Neon Pig"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El proyecto se centra en la residencia del compositor argentino Fernando Garnero en el marco del festival australiano BIFEM, junto a Argonaut, el ensamble residente del festival, la directora de orquesta Elena Schwarz y el sound-designer y lutier Benjamin Kolaitis. &quot;}\" data-sheets-userformat=\"{&quot;2&quot;:513,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0}\">El proyecto se centra en la residencia del compositor argentino Fernando Garnero en el marco del festival australiano BIFEM, junto a Argonaut, el ensamble residente del festival, la directora de orquesta Elena Schwarz y el sound-designer y lutier Benjamin Kolaitis. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto se centra en la residencia del compositor argentino Fernando Garnero en el marco del festival australiano BIFEM, junto a Argonaut, el ensamble residente del festival, la directora de orquesta Elena Schwarz y el sound-designer y lutier Benjamin Kolaitis.<\/p>\n","protected":false},"author":1,"featured_media":7042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[53],"tags":[],"class_list":["post-7041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-generales"],"lang":"es","translations":{"es":7041},"pll_sync_post":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/7041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/comments?post=7041"}],"version-history":[{"count":0,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/posts\/7041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media\/7042"}],"wp:attachment":[{"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/media?parent=7041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/categories?post=7041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ibermusicas.org\/index.php\/wp-json\/wp\/v2\/tags?post=7041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}